{"id":5863,"date":"2019-07-15T09:13:54","date_gmt":"2019-07-15T09:13:54","guid":{"rendered":"http:\/\/www.residenzedelbosco.com\/chemical\/?post_type=product&#038;p=5863"},"modified":"2022-05-24T12:48:02","modified_gmt":"2022-05-24T12:48:02","slug":"mogol","status":"publish","type":"product","link":"https:\/\/chemical-roadmaster.com\/en\/product\/mogol\/","title":{"rendered":"MOGOL"},"content":{"rendered":"<p><span style=\"color: #008000;\">APPLICATION:<\/span><\/p>\n<p>Mogol \u00e8 un pulitore acido viscosizzato, specifico per eliminare dai pavimenti residui di difficile rimozione, quali calce, cemento, efflorescenze saline, ecc. Il prodotto \u00e8 ottimo anche per la pulizia di balconi, terrazze, porticati, garage, scale in pietra e facciate, dai quali rimuove smog, segni neri, incrostazioni, graffiti e contaminazioni di varia natura. Il prodotto \u00e8 molto efficace e con la sua viscosit\u00e0 aderisce anche alle superfici verticali. Se correttamente usato pulisce a fondo la maggior parte delle superfici edili, dalle quali elimina i segni del tempo, rimettendole a nuovo.<\/p>\n<p><span style=\"color: #515151; font-size: 16px; font-weight: bold;\">ARE YOU INTERESTED IN THIS PRODUCT?<\/span><br \/>\nIf you wish to know more about this product please fill the form and we will be happy to get back to you with more information.<\/p>\n<div class=\"frm_forms  with_frm_style frm_style_stile-di-formidable\" id=\"frm_form_1_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form\" id=\"form_contact-form\" action=\"\"  >\n<div class=\"frm_form_fields\">\n<fieldset>\n<legend class=\"frm_screen_reader\">Contact Us<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"1\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_1\" id=\"frm_hide_fields_1\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_1\" name=\"frm_submit_entry_1\" value=\"5cb61eca2b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/product\/5863\" \/><div id=\"frm_field_6_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_qskov\" id=\"field_qskov_label\" class=\"frm_primary_label\">User class\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[6]\" id=\"field_qskov\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Tipologia di contatto is invalid\" aria-invalid=\"false\"  >\n\t\t<option  value=\"\" selected='selected'> <\/option><option  value=\"Privato\">Private<\/option><option  value=\"Azienda\">Company<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_1_container\" class=\"frm_form_field form-field  frm_top_container frm_full\">\r\n    <label for=\"field_qh4icy\" id=\"field_qh4icy_label\" class=\"frm_primary_label\">Company\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_qh4icy\" name=\"item_meta[1]\" value=\"\"  data-invmsg=\"Name non \u00e8 valido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_7_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_yrkok\" id=\"field_yrkok_label\" class=\"frm_primary_label\">Name and Surname\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_yrkok\" name=\"item_meta[7]\" value=\"\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Name non \u00e8 valido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_13_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_ayw1s\" id=\"field_ayw1s_label\" class=\"frm_primary_label\">For which product do you want to receive information?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_ayw1s\" name=\"item_meta[13]\" value=\"\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Testo non \u00e8 valido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_3_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_29yf4d\" id=\"field_29yf4d_label\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_29yf4d\" name=\"item_meta[3]\" value=\"\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Please enter a valid email address\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_8_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_ea85f\" id=\"field_ea85f_label\" class=\"frm_primary_label\">Phone\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_ea85f\" name=\"item_meta[8]\" value=\"\"  data-invmsg=\"Phone non \u00e8 valido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_9_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_rw105\" id=\"field_rw105_label\" class=\"frm_primary_label\">City and country\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_rw105\" name=\"item_meta[9]\" value=\"\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Testo non \u00e8 valido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_5_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_9jv0r1\" id=\"field_9jv0r1_label\" class=\"frm_primary_label\">Message\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[5]\" id=\"field_9jv0r1\" rows=\"5\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" aria-required=\"true\" data-invmsg=\"Messaggio is invalid\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_10_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container vertical_radio\">\r\n    <div  id=\"field_ng6tw_label\" class=\"frm_primary_label\">\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_ng6tw_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_10-0\"><label for=\"field_ng6tw-0\"><input type=\"checkbox\" name=\"item_meta[10][]\" id=\"field_ng6tw-0\" value=\"Dichiaro di aver preso visione della &lt;a href=&quot;https:\/\/chemical-roadmaster.com\/privacy-policy-ita\/&quot;&gt;Privacy Policy&lt;\/a&gt;\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" data-invmsg=\"This field is invalid\" aria-invalid=\"false\"   aria-required=\"true\"  \/> I declare that I have read the <a href=\"https:\/\/chemical-roadmaster.com\/en\/privacy-policy-ita\/\">Privacy Policy<\/a><\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_10-1\"><label for=\"field_ng6tw-1\"><input type=\"checkbox\" name=\"item_meta[10][]\" id=\"field_ng6tw-1\" value=\"Accetto di ricevere promozioni e sconti\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\" data-invmsg=\"This field is invalid\" aria-invalid=\"false\"   \/> I agree to receive discounts and promotions<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_11_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_pax1b_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_14_container\" class=\"frm_form_field form-field  frm_none_container\">\n    <label for=\"g-recaptcha-response\" id=\"field_4yte0_label\" class=\"frm_primary_label\">reCAPTCHA\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\n    <\/label>\n    \n    \n    \n<\/div>\n<div id=\"frm_field_17_container\" class=\"frm_form_field form-field  frm_none_container\">\n    <label for=\"g-recaptcha-response\" id=\"field_j2rc8_label\" class=\"frm_primary_label\">reCAPTCHA\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\n    <\/label>\n    \n    \n    \n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t\t<div class=\"frm__66407277085d8\">\n\t\t\t\t<label for=\"frm_email_1\" >\n\t\t\t\t\tIf you are human, leave this field blank.\t\t\t\t<\/label>\n\t\t\t\t<input  id=\"frm_email_1\" type=\"text\" class=\"frm_verify\" name=\"frm__66407277085d8\" value=\"\" autocomplete=\"false\"  \/>\n\t\t\t<\/div>\n\t\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit\" type=\"submit\"  >Send<\/button>\r\n\r\n<\/div><\/div>\n<\/fieldset>\n<\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n\n<p><span style=\"color: #515151; font-size: 16px; font-weight: bold;\">FOLLOW US<\/span><br \/>\n<a href=\"https:\/\/www.facebook.com\/ChemicalRoadmaster\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone size-full wp-image-7610\" src=\"https:\/\/chemical-roadmaster.com\/wp-content\/uploads\/2020\/05\/facebook.png\" alt=\"\" width=\"32\" height=\"32\" \/><\/a> <a href=\"https:\/\/www.instagram.com\/chemical.roadmaster\/?hl=it\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone size-full wp-image-7611\" src=\"https:\/\/chemical-roadmaster.com\/wp-content\/uploads\/2020\/05\/instagram.png\" alt=\"\" width=\"32\" height=\"32\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Pulitore acido viscoso <\/strong><strong>per facciate e pavimenti<\/strong><br \/>\n<script>function myscroll(){ window.scrollBy(0,600);} <\/script><button id=\"but\" style=\"background-color: #ffd700; border-color: #ffd700; padding: 15px;\">Maggiori Informazioni<\/button><script>\nvar link  = window.location.href;\nif(link.includes(\"www.chemical-roadmaster.com\/en\/\")){\ndocument.getElementById(\"but\").innerHTML = \"More Info \"; \n}\n<\/script><\/p>","protected":false},"featured_media":6536,"template":"","meta":{"_acf_changed":false},"product_cat":[543,497,767,538,425],"product_tag":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/product\/5863"}],"collection":[{"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/product\/5863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/media\/6536"}],"wp:attachment":[{"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/media?parent=5863"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/product_cat?post=5863"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chemical-roadmaster.com\/en\/wp-json\/wp\/v2\/product_tag?post=5863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}